{"id":453,"date":"2019-03-02T15:10:40","date_gmt":"2019-03-02T15:10:40","guid":{"rendered":"https:\/\/www.seguros-camiones.com\/blog\/?p=453"},"modified":"2024-08-03T04:44:04","modified_gmt":"2024-08-03T04:44:04","slug":"conductores-imprudentes-en-espana","status":"publish","type":"post","link":"https:\/\/www.seguros-camiones.com\/blog\/conductores-imprudentes-en-espana\/03\/2019\/","title":{"rendered":"\u00bfConductores imprudentes en Espa\u00f1a?"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Son muchas y variadas las causas que provocan accidentes viales. En Espa\u00f1a, hay conductores imprudentes, en especial entre los m\u00e1s j\u00f3venes, que realizan pr\u00e1cticas temerarias al volante. Por ende, ponen en peligro su vida y las de los dem\u00e1s.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Las infracciones contra la Seguridad Vial, est\u00e1n alrededor del \u00a035% de todos los delitos \u00a0que se producen en el pa\u00eds. \u00a0La Polic\u00eda llama la atenci\u00f3n \u00a0a los j\u00f3venes conductores sobre los retos que pueden costarles la vida. Tales \u00a0como &#8216;Momo&#8217; o &#8216;Bird Box Challenge&#8217;.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Esta moda\u00a0 entre los j\u00f3venes conductores es copiada de la pel\u00edcula de Netflix, donde Sandra Bullock, conduce con los ojos vendados para sobrevivir. Esta pr\u00e1ctica es ahora com\u00fan en la juventud espa\u00f1ola. Es uno de los retos m\u00e1s peligrosos que ya ha costado varios accidentes.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Estudios realizados indican que m\u00e1s de cuatro millones de conductores en Espa\u00f1a son imprudentes al manejar.<\/strong> Es lamentable que este tipo de pr\u00e1cticas imprudentes sean las responsables de que ocurran 1 de cada 5 accidentes viales. Ocasionando adem\u00e1s victimas mortales en el siniestro<strong>. As\u00ed lo confirma un informe suministrado por un comparador de seguros de acierto.com. <\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Otras causas comunes e imprudentes son manejar bajo el efecto del alcohol o las drogas. Tambi\u00e9n ambos a la vez, alcohol y drogas, lo cual es lo m\u00e1s corriente entre los\u00a0 espa\u00f1oles. Este factor representa el 60% de las imprudencias cometidas por los espa\u00f1oles al manejar.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Las estad\u00edsticas indican que casi el 50% de los espa\u00f1oles indica que han conducido, por lo menos una vez despu\u00e9s de consumir bebidas alcoh\u00f3licas. Adem\u00e1s todos, hasta el 14% \u00a0han manejado a sabiendas que est\u00e1n superando \u00a0el nivel legal de alcoholemia. Otros delitos en los que incurren son superar los 200 km\/h en carretera, circular sin carnet\u00a0 y negarse a realizar los controles exigidos.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Un dato \u00a0curioso es que una gran cantidad de estos conductores imprudentes (m\u00e1s de 9.000.000) desconocen que estas acciones los pueden mandar directo a la c\u00e1rcel.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><strong>Otras acciones de los conductores imprudentes<\/strong><\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Cada vez es m\u00e1s com\u00fan que los j\u00f3venes innoven \u00a0retos\u00a0 que se hacen virales. Los m\u00e1s actuales con alto riesgo personal y para la seguridad social son el Baby Shark Challenge y el In My Feelings Challenge. Desaf\u00edos que implican bajarse del coche en movimiento y bailar a su lado.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Asimismo, otras pr\u00e1cticas igualmente peligrosas son las carreras de trompos o grabar videos cuando manejan a alta velocidad. La edad m\u00e1s com\u00fan entre los j\u00f3venes que frecuentemente realizan estos actos es entre 18 y 24 a\u00f1os de edad.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Igualmente los j\u00f3venes graban cuando manejan en sentido contrario o con la moto mirando hacia atr\u00e1s. Todas estas conductas son realmente imprudentes que ponen en riesgo a su vida y la de otros. Act\u00faan, sin duda alguna,\u00a0 con alto nivel de imprudencia e irresponsabilidad. Sin contar que tendr\u00e1n una pena de c\u00e1rcel entre 6 meses y 2 a\u00f1os. Adem\u00e1s <strong>el seguro de veh\u00edculos no ser\u00e1 responsable por estos actos. <\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Todo conductor y los j\u00f3venes en especial deben considerar que a pesar de tener el veh\u00edculo asegurado a todo riesgo, existen circunstancias que este no cubre. Las compa\u00f1\u00edas aseguradoras no solamente no cubrir\u00e1n los gastos en que ha incurrido, sino que adem\u00e1s el infractor deber\u00e1 responder por la multa que le ser\u00e1 impuesta.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Por esta raz\u00f3n es conveniente que se entere de las situaciones\u00a0 consideradas negligencias por parte del conductor. Consulte las diez circunstancias,\u00a0recogidas por la Direcci\u00f3n General de Tr\u00e1fico (DGT)\u00a0en su\u00a0revista del mes de marzo, donde se analiza cada caso particular.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Finalmente, es muy importante elegir un buen seguro que tenga la mayor\u00a0 cobertura para su veh\u00edculo. Puede\u00a0<strong><a href=\"https:\/\/seguros-de-coche.seguros-generales.es\/\" target=\"_blank\" rel=\"noopener\">comparar las opciones de seguro de coche<\/a><\/strong>\u00a0para poder elegir la que mejor se adapte a su necesidad.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Son muchas y variadas las causas que provocan accidentes viales. En Espa\u00f1a, hay conductores imprudentes, en especial entre los m\u00e1s j\u00f3venes, que realizan pr\u00e1cticas temerarias al volante. Por ende, ponen en peligro su vida y las de los dem\u00e1s. Las infracciones contra la Seguridad Vial, est\u00e1n alrededor del \u00a035% de todos los delitos \u00a0que se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":456,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accidentes"],"_links":{"self":[{"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/posts\/453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/comments?post=453"}],"version-history":[{"count":1,"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/posts\/453\/revisions"}],"predecessor-version":[{"id":1341,"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/posts\/453\/revisions\/1341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/media\/456"}],"wp:attachment":[{"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/media?parent=453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/categories?post=453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/tags?post=453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}