{"id":620,"date":"2019-10-14T12:59:01","date_gmt":"2019-10-14T12:59:01","guid":{"rendered":"https:\/\/www.seguros-camiones.com\/blog\/?p=620"},"modified":"2024-08-03T04:19:24","modified_gmt":"2024-08-03T04:19:24","slug":"llega-el-100-electrico-man-tgm-26-360-de-man-trucksbus","status":"publish","type":"post","link":"https:\/\/www.seguros-camiones.com\/blog\/llega-el-100-electrico-man-tgm-26-360-de-man-trucksbus\/10\/2019\/","title":{"rendered":"Llega el 100% el\u00e9ctrico MAN TGM 26.360 de MAN Trucks&#038;Bus"},"content":{"rendered":"<p>Los veh\u00edculos de combusti\u00f3n son sometidos a mayores restricciones cada d\u00eda, como consecuencias de la emisi\u00f3n de CO<sub>2<\/sub>. Uno de los sectores que mayor incidencia tiene en la contaminaci\u00f3n, es el transporte de carga urbano. Y este segmento del transporte, se ha incrementado notoriamente en las grandes ciudades.<\/p>\n<p>La empresa MAN Trucks &amp; Bus, ha presentado su cami\u00f3n de reparto MAN TGM 26.360 E totalmente el\u00e9ctrico. Un veh\u00edculo de tres ejes, con 360 CV de potencia m\u00e1xima y una capacidad de carga de 26000 kilos, totalmente el\u00e9ctrico. Que no solo elimina la contaminaci\u00f3n por CO<sub>2<\/sub>, sino que reduce a cero la contaminaci\u00f3n ac\u00fastica<\/p>\n<p>Un motor el\u00e9ctrico, montado en la parte central de un bastidor r\u00edgido 6&#215;2, que genera una potencia m\u00e1xima de 360 CV (264kW). Este motor transmite 3100 Nm de par m\u00e1ximo a las ruedas, permite movilizar una carga de hasta 26 Tn, sin necesidad de caja de cambios.<\/p>\n<p>Su sistema de almacenamiento de energ\u00eda, est\u00e1 constituido por 12 bater\u00edas de Ion-Litio. Este conjunto de bater\u00edas, situado a lo largo del bastidor, es capaz de almacenar 185kWh. Con una autonom\u00eda de 180 km, lo hacen muy atractivo para el transporte urbano.<\/p>\n<p>Otro gran atractivo, es que las bater\u00edas pueden ser cargadas ya sea con corriente continua DC entre 380 y 400 voltios, para unos 150 Kw-h. As\u00ed como tambi\u00e9n con corriente alterna AC de 220 voltios. La primera opci\u00f3n permite una carga r\u00e1pida de 1 hora 30 minutos. Mientras que la segunda opci\u00f3n requiere 5 horas, 30 minutos para almacenar 22 Kw-h, y para almacenar 44 Kw-h, son requeridas 8 horas, 30 minutos.<\/p>\n<p>Por otra parte, para hacer m\u00e1s eficiente la recarga de las bater\u00edas, el MAN TGM 26360 E viene dotado de una toma de corriente a cada lado del veh\u00edculo. Estas tomas disponen de los conectores espec\u00edficos para la corriente alterna AC y corriente continua DC. Dispone adem\u00e1s de indicadores, uno para ver la cantidad de carga disponible y otro para visualizar la capacidad de energ\u00eda restante<\/p>\n<p>El MAN TGM 26360 E, ha sido dise\u00f1ado para uso en el transporte urbano, con diversas aplicaciones. Estas van desde la carrocer\u00eda para recogida de basura, hasta el furg\u00f3n frigor\u00edfico y l\u00f3gicamente el furg\u00f3n para cargas no perecederas. En todos estos modelos, los accesorios o equipamientos adicionales son tambi\u00e9n el\u00e9ctricos.<\/p>\n<blockquote><p>Revise ahora los mejores <a href=\"https:\/\/www.seguroslowcost.es\/seguros-camion-lowcost.html\" target=\"_blank\" rel=\"noopener\">seguros de camiones low cost<\/a> para contar siempre con la mejor opci\u00f3n<\/p><\/blockquote>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.seguros-camiones.com\/blog\/llega-el-100-electrico-man-tgm-26-360-de-man-trucksbus\/10\/2019\/#Diferentes_empresas_pondran_a_prueba_su_funcionamiento\" >Diferentes empresas pondr\u00e1n a prueba su funcionamiento<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.seguros-camiones.com\/blog\/llega-el-100-electrico-man-tgm-26-360-de-man-trucksbus\/10\/2019\/#Ficha_Tecnica\" >Ficha T\u00e9cnica<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Diferentes_empresas_pondran_a_prueba_su_funcionamiento\"><\/span><strong>Diferentes empresas pondr\u00e1n a prueba su funcionamiento<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Este veh\u00edculo a\u00fan no se encuentra disponible, sin embargo, <strong>empresas de transporte como Mercadona, \u00a0Acotral, Grupo Mazo y Lidl Espa\u00f1a, van a poner a prueba el MAN TGM 26360 E.<\/strong> Para ello cada una de estas empresas, recibir\u00e1 un prototipo, de esta forma podr\u00e1n comprobar las ventajas del veh\u00edculo.<\/p>\n<div class=\"su-box su-box-style-default\" id=\"\" style=\"border-color:#c93200;border-radius:3px;max-width:none\"><div class=\"su-box-title\" style=\"background-color:#fc651f;color:#FFFFFF;border-top-left-radius:1px;border-top-right-radius:1px\">T\u00edtulo de caja<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:1px;border-bottom-right-radius:1px\">El MAN TGM 26360 E permite disfrutar de una lujosa y c\u00f3moda cabina. Presenta un reloj indicador, con dos posiciones OFF y ON. Al accionar el contacto, la aguja del reloj que se encuentra ca\u00edda, se sit\u00faa en la posici\u00f3n OFF.<\/div><\/div>\n<p>Durante los primeros 8 segundos, el veh\u00edculo realiza un chequeo, una vez finalizado, la aguja se coloca en la posici\u00f3n ON. El accionar de la bomba de la direcci\u00f3n emite un peque\u00f1o zumbido, indicando que el veh\u00edculo est\u00e1 listo para arrancar. El movimiento se acciona mediante una palanca de solamente dos posiciones D y R, para circular hacia adelante o hacia atr\u00e1s.<\/p>\n<p>El inicio del movimiento es sumamente silencioso, puede ser suave si se pisa con cierto tacto el acelerador. Pero tambi\u00e9n puede ser muy agresivo si se pisa a fondo el acelerador. Desde el segundo cero, ya se dispone de los 3100 Nm del par, y lo m\u00e1s importante es que no requiere de caja de cambios.<\/p>\n<p>El reloj indicador, presenta una zona verde de uso eficiente de la autonom\u00eda al centro y dos zonas rojas de uso ineficiente de la autonom\u00eda en los extremos. De acuerdo a la aceleraci\u00f3n, la aguja se sit\u00faa en estas zonas. A la izquierda en rojo indica una baja aceleraci\u00f3n, a la derecha roja para una alta aceleraci\u00f3n. Finalmente el verde para una aceleraci\u00f3n normal.<\/p>\n<p><strong>Para regenerar las bater\u00edas, es indispensable la utilizaci\u00f3n del freno, de manera progresiva.<\/strong> Para activar este freno regenerador, cuanta con una palanca, situada debajo y a la derecha del volante. Esta palanca tiene tres posiciones, que activan el freno el\u00e9ctrico de tres puntos<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"nBHctHKMZS\"><p><a href=\"https:\/\/www.seguros-camiones.com\/blog\/camiones-con-pluma-requisitos-y-habilidades\/09\/2019\/\">Camiones con pluma&#8230; Requisitos y habilidades<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abCamiones con pluma&#8230; Requisitos y habilidades\u00bb \u2014 Blog de Noticias de Camiones, Cabezas Tractoras, Furgones Pesados y Semirremolques\" src=\"https:\/\/www.seguros-camiones.com\/blog\/camiones-con-pluma-requisitos-y-habilidades\/09\/2019\/embed\/#?secret=ZeiLudKGzL#?secret=nBHctHKMZS\" data-secret=\"nBHctHKMZS\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>El MAN TGM 26360 E, trabaja con una tensi\u00f3n m\u00e1xima de 800 voltios. Como medida de seguridad, el veh\u00edculo cuenta con un pulsador interno de parada de emergencia. Al ser presionado, se desconecta la alta tensi\u00f3n. Sin embargo el resto de los implementos y accesorios, que funcionan con los 12 voltios convencionales, contin\u00faan estando operativos<\/p>\n<p>Con la colaboraci\u00f3n de estas empresas, se podr\u00e1 mejorar el producto, hasta el modelo de serie. En este sentido, la producci\u00f3n en serie se estima para mediados de la pr\u00f3xima d\u00e9cada. Lo que con seguridad ofrecer\u00e1 una alternativa para el transporte urbano de carga, con una capacidad de movilizaci\u00f3n de 21 ton.<\/p>\n<blockquote><p>Contrate siempre el mejor <a href=\"https:\/\/www.seguros-camiones.com\/\">seguro de camiones<\/a> para estar completamente protegido contra cualquier eventualidad<\/p><\/blockquote>\n<h2><span class=\"ez-toc-section\" id=\"Ficha_Tecnica\"><\/span><strong>Ficha T\u00e9cnica<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Modelo: MAN TGM 26360 E 6&#215;2-4LL<\/p>\n<p>Tipo de segmento: Transporte de reparto<br \/>\nMotor: PSM (motor s\u00edncrono de excitaci\u00f3n permanente)<br \/>\nNormativa sobre emisiones: 100% el\u00e9ctrico, Cero emisiones<br \/>\nPotencia: 264 kW (360 CV)<br \/>\nPar: 3.100Nm<br \/>\nCaja de cambios: Desmultiplicaci\u00f3n fija sin caja de cambios manual<br \/>\nDesmultiplicaci\u00f3n total (incl. eje trasero): i =\u00a07,5 (velocidad del motor a 85 km\/h = 3.580 rpm)<br \/>\nDistancia entre ejes \/ voladizo: 4.725 mm + 1.350 mm \/ 2.675 mm<br \/>\nPeso m\u00e1ximo autorizado (t\u00e9cnico): 26.000 kg<br \/>\nTara con carrocer\u00eda: 14.710 kg<br \/>\nAutonom\u00eda: 180 Km sin cargas intermedias<br \/>\nBater\u00edas: 12 packs bater\u00edas ion litio capacidad 185 kWh<\/p>\n<blockquote><p>Para encontrar y contratar el mejor seguro, utilice siempre el mejor <a href=\"https:\/\/seguros-de-camion.seguros-generales.es\/\" target=\"_blank\" rel=\"noopener\">comparador de seguros de cami\u00f3n<\/a><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Los veh\u00edculos de combusti\u00f3n son sometidos a mayores restricciones cada d\u00eda, como consecuencias de la emisi\u00f3n de CO2. Uno de los sectores que mayor incidencia tiene en la contaminaci\u00f3n, es el transporte de carga urbano. Y este segmento del transporte, se ha incrementado notoriamente en las grandes ciudades. La empresa MAN Trucks &amp; Bus, ha [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":621,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[552],"tags":[],"class_list":["post-620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-camiones-electricos"],"_links":{"self":[{"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/posts\/620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/comments?post=620"}],"version-history":[{"count":1,"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/posts\/620\/revisions"}],"predecessor-version":[{"id":1307,"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/posts\/620\/revisions\/1307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/media\/621"}],"wp:attachment":[{"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/media?parent=620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/categories?post=620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.seguros-camiones.com\/blog\/wp-json\/wp\/v2\/tags?post=620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}